{"id":638,"date":"2018-12-18T15:20:02","date_gmt":"2018-12-18T15:20:02","guid":{"rendered":"http:\/\/ceca.icom.cust.oxymium.net\/conferencias\/proxima-conferencia\/"},"modified":"2026-06-18T06:01:26","modified_gmt":"2026-06-18T06:01:26","slug":"proxima-conferencia","status":"publish","type":"page","link":"https:\/\/ceca.mini.icom.museum\/es\/conferencias\/proxima-conferencia\/","title":{"rendered":"Conferencia anual"},"content":{"rendered":"<p>\u00danase a nosotros en <strong>\u00abLos museos en tiempos divididos: \u00bfc\u00f3mo fomentar el di\u00e1logo, el cuidado y un sentido de pertenencia?\u00bb<\/strong>, la pr\u00f3xima Conferencia anual del ICOM \u2013 CECA (Comit\u00e9 para la Educaci\u00f3n y la Acci\u00f3n Cultural), que se celebrar\u00e1 en Yakarta \u2013 Indonesia, del 10 al 14 de noviembre de 2026.<\/p>\n<p>El evento est\u00e1 organizado por Musee ID, en colaboraci\u00f3n con el Gobierno Provincial de Yakarta, The Good News From Indonesia, ICOM Alemania y con el apoyo de ICOM Indonesia.<\/p>\n<div style=\"display:flex;align-items:center;gap:20px;margin:12px 0\">\n<img decoding=\"async\" src=\"https:\/\/commons.wikimedia.org\/wiki\/Special:FilePath\/Coat_of_arms_of_Jakarta.svg\" alt=\"Gobierno Provincial de Yakarta\" style=\"height:44px;width:auto\"><br \/>\n<img decoding=\"async\" src=\"https:\/\/icom-deutschland.de\/wp-content\/themes\/icom\/img\/ICOM Logo Deutschland.svg\" alt=\"ICOM Alemania\" style=\"height:28px;width:auto\"><br \/>\n<img decoding=\"async\" src=\"https:\/\/ceca.mini.icom.museum\/wp-content\/uploads\/sites\/5\/2026\/06\/Logo-ICOM-Indonesia-scaled.png\" alt=\"ICOM Indonesia\" style=\"height:28px;width:auto\">\n<\/div>\n<p>Para los asistentes e interesados, existe un sitio web dedicado a la Conferencia anual: <a href=\"https:\/\/icomcecaconference.com\/\">CECA Jakarta 2026<\/a><\/p>\n<p>Los principales temas, los detalles sobre la inscripci\u00f3n y las actualizaciones tambi\u00e9n se compartir\u00e1n a continuaci\u00f3n:<\/p>\n<p><strong>La Conferencia se centrar\u00e1 en actividades de educaci\u00f3n muse\u00edstica que<\/strong><\/p>\n<ul>\n<li>Reduzcan la fragmentaci\u00f3n social mediante la implementaci\u00f3n de estrategias educativas inclusivas basadas en la empat\u00eda.<\/li>\n<li>Cultiven espacios seguros para el di\u00e1logo cr\u00edtico, permitiendo que comunidades diversas intercambien perspectivas y reconcilien diferencias.<\/li>\n<li>Refuercen el sentido de propiedad colectiva del patrimonio cultural en medio de la polarizaci\u00f3n global y local.<\/li>\n<li>Aprovechen narrativas humanistas y una pedagog\u00eda innovadora para involucrar a p\u00fablicos marginados o subrepresentados.<\/li>\n<\/ul>\n<hr \/>\n<h3><strong>Temas<\/strong><\/h3>\n<p>El tema \u00abLos museos en tiempos divididos: \u00bfc\u00f3mo fomentar el di\u00e1logo, el cuidado y un sentido de pertenencia?\u00bb abarca los siguientes t\u00f3picos:<\/p>\n<ul>\n<li><strong>Los museos como agentes de cohesi\u00f3n social:<\/strong> Estrategias para sanar fracturas sociales y fomentar la reconciliaci\u00f3n a trav\u00e9s de la programaci\u00f3n cultural. Esta perspectiva, sin embargo, puede ser cuestionada: \u00bfa qu\u00e9 tipo de \u00abdivisiones\u00bb nos referimos: polarizaci\u00f3n, fragmentaci\u00f3n, pluralizaci\u00f3n de voces? \u00bfSon estas fracturas algo que debe resolverse, o tensiones constitutivas de lo social que deben hacerse inteligibles? \u00bfPuede concebirse el museo como externo a estas din\u00e1micas, o como un actor ya inscrito en estas recomposiciones?<\/li>\n<li><strong>Pedagog\u00edas inclusivas en un mundo polarizado:<\/strong> Desarrollar marcos educativos que tengan en cuenta la diversidad cognitiva, f\u00edsica y cultural. Este enfoque nos invita a precisar los registros de divisi\u00f3n en juego (social, cultural, epist\u00e9mico) y a cuestionar las condiciones bajo las cuales la inclusi\u00f3n no apunta meramente a la integraci\u00f3n, sino al reconocimiento del desacuerdo y la pluralidad.<\/li>\n<li><strong>El poder de las narrativas:<\/strong> Utilizar relatos personales y colectivos para desmantelar estereotipos y humanizar \u00abal otro\u00bb. Esta orientaci\u00f3n plantea preguntas sobre el estatus de las narrativas: \u00bfcontribuyen a la b\u00fasqueda de consenso, o a visibilizar perspectivas irreductiblemente plurales, incluso conflictivas?<\/li>\n<li><strong>Empat\u00eda digital y conectividad:<\/strong> Explorar c\u00f3mo las plataformas digitales pueden utilizarse para construir comprensi\u00f3n y cuidado en lugar de c\u00e1maras de eco. Esto requiere examinar las formas contempor\u00e1neas de conflicto y la circulaci\u00f3n del discurso, as\u00ed como la manera en que los entornos digitales podr\u00edan acoger el disenso en lugar de atenuarlo.<\/li>\n<li><strong>Curadur\u00eda y programaci\u00f3n participativas:<\/strong> Transformar los museos de autoridades verticales en plataformas participativas que empoderen las voces locales. Reflexionar sobre estas pr\u00e1cticas implica clarificar qu\u00e9 se entiende por di\u00e1logo: \u00bfes una forma de mediaci\u00f3n consensual, o un espacio de confrontaci\u00f3n razonada que acepta el conflicto regulado?<\/li>\n<li><strong>Patrimonio e identidad en transici\u00f3n global:<\/strong> Navegar el papel de los museos en el mantenimiento de un sentido de pertenencia en medio de la migraci\u00f3n, la urbanizaci\u00f3n y el r\u00e1pido cambio social. Esta noci\u00f3n de pertenencia tambi\u00e9n requiere clarificaci\u00f3n: \u00bfpertenencia a qu\u00e9: a una comunidad local, a una naci\u00f3n, o a una humanidad compartida? \u00bfPueden los museos concebirse como espacios de hospitalidad, donde uno puede pertenecer sin tener que alinearse?<\/li>\n<\/ul>\n<hr \/>\n<h3><strong>Estructura de la Conferencia<\/strong><\/h3>\n<p><strong>La Conferencia incluye:<\/strong><\/p>\n<ul>\n<li>Conferencias magistrales (keynotes)<\/li>\n<li>Presentaciones: comunicaciones de investigaci\u00f3n (20\u2032), comunicaciones tem\u00e1ticas (15\u2032), mercado de ideas (7\u2032), p\u00f3sters (formato impreso)<\/li>\n<li>Talleres de los Grupos de inter\u00e9s especial (GIE) del CECA<\/li>\n<li>Presentaci\u00f3n y ceremonia de premios (Premio Investigaci\u00f3n, Premio Best Practice, Premio Red de J\u00f3venes Miembros)<\/li>\n<li>Visitas educativas a museos<\/li>\n<li>Espect\u00e1culos culturales<\/li>\n<li>Excursi\u00f3n a museos, monumentos y sitios de Yakarta<\/li>\n<\/ul>\n<hr \/>\n<h3><strong>Idiomas<\/strong><\/h3>\n<p>Los idiomas oficiales de la Conferencia son el ingl\u00e9s y el indonesio, por lo que la interpretaci\u00f3n biling\u00fce solo se proporcionar\u00e1 durante las conferencias magistrales, las comunicaciones de investigaci\u00f3n y tem\u00e1ticas, el mercado de ideas y las presentaciones y ceremonias de premios. En este sentido, los ponentes que utilicen el franc\u00e9s o el espa\u00f1ol en su presentaci\u00f3n deber\u00e1n asegurarse de que todas sus diapositivas est\u00e9n en ingl\u00e9s, o con traducci\u00f3n al ingl\u00e9s, y que el texto incluido en cada diapositiva sea lo m\u00e1s detallado posible.<\/p>\n<p>Los talleres podr\u00e1n impartirse en ingl\u00e9s, franc\u00e9s o espa\u00f1ol.<\/p>\n<p>Las visitas educativas se realizar\u00e1n \u00fanicamente en ingl\u00e9s.<\/p>\n<hr \/>\n<h3><strong>Presentaciones \u2013 Fechas importantes<\/strong><\/h3>\n<p>Los miembros del ICOM que deseen realizar una presentaci\u00f3n en la Conferencia de Yakarta (comunicaciones de investigaci\u00f3n \/ tem\u00e1ticas, mercado de ideas, talleres, p\u00f3sters) deben cumplimentar y enviar el formulario de solicitud en l\u00ednea alojado en el sitio web de la Conferencia de Yakarta <a href=\"https:\/\/www.icomcecaconference.com\/\">https:\/\/www.icomcecaconference.com\/<\/a>.<\/p>\n<ul>\n<li><strong>Fecha l\u00edmite de env\u00edo de comunicaciones:<\/strong> 1 de junio<\/li>\n<li><strong>Notificaci\u00f3n a los ponentes preseleccionados para la Conferencia:<\/strong> 1 de julio<\/li>\n<li><strong>Fecha l\u00edmite de confirmaci\u00f3n \/ inscripci\u00f3n de los ponentes preseleccionados:<\/strong> 15 de septiembre<\/li>\n<\/ul>\n<hr \/>\n<h3><strong>Premios CECA \u2013 Fechas importantes<\/strong><\/h3>\n<ul>\n<li>Premio Best Practice<\/li>\n<li>Premio Investigaci\u00f3n<\/li>\n<li>Premio J\u00f3venes Miembros<\/li>\n<\/ul>\n<ul>\n<li><strong>Fecha l\u00edmite de presentaci\u00f3n para los premios:<\/strong> 4 de mayo<\/li>\n<li><strong>Nominaci\u00f3n de los ganadores:<\/strong> 10 de julio<\/li>\n<\/ul>\n<hr \/>\n<h3><strong>Sedes y visitas<\/strong><\/h3>\n<p>La Conferencia se celebrar\u00e1 exclusivamente de forma presencial. Parte de las presentaciones podr\u00e1n ofrecerse en l\u00ednea o grabarse y estar disponibles en YouTube.<\/p>\n<p><strong>D\u00eda 0: Llegada y preinscripci\u00f3n (09\/11)<\/strong><br \/>\nSe espera que los participantes lleguen a Yakarta. Para garantizar un inicio fluido de la conferencia, se celebrar\u00e1 una sesi\u00f3n de preinscripci\u00f3n en:<br \/>\nSede: Grand Theater, Taman Ismail Marzuki (Centro de Arte y Cultura de Yakarta)<br \/>\nHorario: 10:30 \u2013 17:00 WIB<\/p>\n<p><strong>D\u00eda 1: Inauguraci\u00f3n &amp; Sesiones plenarias (10\/11)<\/strong><br \/>\nLa conferencia se inaugura oficialmente en el Grand Theater, Taman Ismail Marzuki (Centro de Arte y Cultura de Yakarta). Esta jornada est\u00e1 dedicada a los discursos de bienvenida, las conferencias magistrales, las presentaciones de los ponentes y la ceremonia de premios CECA, en el principal espacio cultural y de artes esc\u00e9nicas de Yakarta.<\/p>\n<p><strong>D\u00eda 2: Patrimonio vivo &amp; Sesiones paralelas (11\/11)<\/strong><br \/>\nLa conferencia se traslada al coraz\u00f3n hist\u00f3rico de la ciudad: el casco antiguo de Yakarta (Kota Tua). Las sesiones paralelas, junto con visitas guiadas a las colecciones, se celebrar\u00e1n simult\u00e1neamente en cuatro instituciones patrimoniales emblem\u00e1ticas:<\/p>\n<ul>\n<li>Museum Bank Indonesia<\/li>\n<li>Museo de Historia de Yakarta (Museum Fatahillah)<\/li>\n<li>Museo de Bellas Artes y Cer\u00e1mica<\/li>\n<li>Museo Wayang (Marionetas)<\/li>\n<\/ul>\n<p><em>Nota para los participantes:<\/em> Las cuatro sedes est\u00e1n situadas dentro del mismo conjunto hist\u00f3rico, a entre 1 y 3 minutos a pie entre s\u00ed. Esta proximidad permite a los participantes moverse libremente entre las sedes y asistir a diferentes presentaciones a lo largo del d\u00eda. Este formato descentralizado ofrece un di\u00e1logo inmersivo dentro del patrimonio vivo de Indonesia, combinando el discurso acad\u00e9mico con la grandeza arquitect\u00f3nica.<\/p>\n<p><strong>D\u00eda 3: Educaci\u00f3n inmersiva e integraci\u00f3n cultural (12\/11)<\/strong><br \/>\nSesi\u00f3n matutina: Centrada en la excelencia pedag\u00f3gica a trav\u00e9s de visitas educativas y talleres interactivos en museos seleccionados de Yakarta.<br \/>\nSesi\u00f3n vespertina: Celebrada en el Museum Bahari (Museo Mar\u00edtimo), con almuerzos ligeros, debates sobre p\u00f3sters, talleres culturales y espect\u00e1culos en vivo.<br \/>\nTarde-noche: Se celebrar\u00e1 una Cena en el Museum Bahari, en honor al rico legado mar\u00edtimo de la ciudad.<\/p>\n<p><strong>D\u00eda 4: Excursiones culturales, Sesi\u00f3n de clausura y Recepci\u00f3n (13\/11)<\/strong><\/p>\n<p>Excursiones culturales, 08:00 \u2013 14:00<br \/>\nLos participantes podr\u00e1n elegir una de las siguientes visitas tem\u00e1ticas organizadas, incluidas en la cuota de inscripci\u00f3n. Las instrucciones para el procedimiento de reserva anticipada se comunicar\u00e1n a su debido tiempo:<\/p>\n<ul>\n<li><strong>Opci\u00f3n 1:<\/strong> Islas arqueol\u00f3gicas de Onrust\u2013Cipir\u2013Kelor<\/li>\n<li><strong>Opci\u00f3n 2:<\/strong> Ruta patrimonial del sur de Yakarta<\/li>\n<li><strong>Opci\u00f3n 3:<\/strong> Parque en miniatura de Indonesia (TMII)<\/li>\n<\/ul>\n<p>14:30 \u2013 18:00<br \/>\n<strong>Sesi\u00f3n de clausura por ICOM Alemania en el Goethe-Institut Indonesia | Jakarta<\/strong><br \/>\n<img decoding=\"async\" style=\"height: 40px;width: auto;margin-top: 8px\" src=\"https:\/\/icom-deutschland.de\/wp-content\/themes\/icom\/img\/ICOM Logo Deutschland.svg\" alt=\"ICOM Alemania\" \/><\/p>\n<p>18:00<br \/>\n<strong>Recepci\u00f3n de clausura por ICOM Alemania en el Goethe-Institut Indonesia | Jakarta<\/strong><\/p>\n<p><strong>D\u00eda 5: Salida y seminario post-conferencia opcional (14\/11)<\/strong><br \/>\nLa conferencia oficial del ICOM-CECA concluye. Los participantes podr\u00e1n partir a su conveniencia o unirse a un seminario post-conferencia opcional en el Museum Bahari Jakarta.<\/p>\n<p>Pr\u00f3ximamente se facilitar\u00e1 informaci\u00f3n sobre el Goethe-Institut Indonesia | Jakarta.<\/p>\n<hr \/>\n<h3><strong>Inscripci\u00f3n<\/strong><\/h3>\n<p>Las personas interesadas en asistir a la Conferencia como participantes (miembros del ICOM, no miembros del ICOM, estudiantes) deben cumplimentar y enviar el formulario de solicitud en l\u00ednea alojado en el sitio web de la Conferencia de Yakarta <a href=\"https:\/\/www.icomcecaconference.com\/\">https:\/\/www.icomcecaconference.com\/<\/a>. La cuota de inscripci\u00f3n tambi\u00e9n se abonar\u00e1 a trav\u00e9s de este sitio. La inscripci\u00f3n para los participantes comienza el 1 de mayo.<\/p>\n<h4><strong>Cuota de inscripci\u00f3n<\/strong><\/h4>\n<table>\n<tbody>\n<tr>\n<th><\/th>\n<th>Early bird (hasta el 15 sept.)<\/th>\n<th>Tard\u00eda (hasta el 31 oct.)<\/th>\n<th>Noviembre<\/th>\n<\/tr>\n<tr>\n<td><strong>Miembros ICOM<\/strong><\/td>\n<td>200 \u20ac<\/td>\n<td>300 \u20ac<\/td>\n<td>350 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><strong>No miembros ICOM<\/strong><\/td>\n<td>300 \u20ac<\/td>\n<td>350 \u20ac<\/td>\n<td>400 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><strong>Estudiantes<\/strong><\/td>\n<td>120 \u20ac<\/td>\n<td>200 \u20ac<\/td>\n<td>250 \u20ac<\/td>\n<\/tr>\n<tr>\n<td><strong>Ponentes<\/strong><\/td>\n<td>200 \u20ac<\/td>\n<td>300 \u20ac<\/td>\n<td>350 \u20ac<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>La cuota de inscripci\u00f3n a la Conferencia incluye<\/strong><\/p>\n<ul>\n<li>Un almuerzo de bienvenida en el Parque Taman Ismail Marzuki el primer d\u00eda (10\/11)<\/li>\n<li>Pausas para caf\u00e9 y almuerzos ligeros (11 \u2013 12 nov.)<\/li>\n<li>Material y merchandising de la Conferencia<\/li>\n<li>Visitas guiadas a los museos<\/li>\n<li>Visita educativa, jornada de espect\u00e1culos culturales y cena en el Museum Bahari Jakarta<\/li>\n<li>Excursi\u00f3n y almuerzos ligeros (13\/11)<\/li>\n<\/ul>\n<p>Los billetes de avi\u00f3n y el alojamiento no est\u00e1n incluidos en la cuota de inscripci\u00f3n, por lo que los ponentes y participantes deber\u00e1n cubrir sus propios gastos.<\/p>\n<hr \/>\n<h3><strong>Contacto<\/strong><\/h3>\n<p>Para cualquier consulta sobre el evento, p\u00f3ngase en contacto con:<br \/>\n<strong>cecaconference1[at]gmail.com<\/strong><\/p>\n<p>Los coordinadores le responder\u00e1n lo antes posible en d\u00edas laborables.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00danase a nosotros en \u00abLos museos en tiempos divididos: \u00bfc\u00f3mo fomentar el di\u00e1logo, el cuidado y un sentido de pertenencia?\u00bb, la pr\u00f3xima Conferencia anual del ICOM \u2013 CECA (Comit\u00e9 para la Educaci\u00f3n y la Acci\u00f3n Cultural), que se celebrar\u00e1 en Yakarta \u2013 Indonesia, del 10 al 14 de noviembre de 2026. El evento est\u00e1 organizado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":137,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"yst_prominent_words":[1756,88,354,92],"class_list":["post-638","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/ceca.mini.icom.museum\/es\/wp-json\/wp\/v2\/pages\/638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ceca.mini.icom.museum\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ceca.mini.icom.museum\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ceca.mini.icom.museum\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ceca.mini.icom.museum\/es\/wp-json\/wp\/v2\/comments?post=638"}],"version-history":[{"count":120,"href":"https:\/\/ceca.mini.icom.museum\/es\/wp-json\/wp\/v2\/pages\/638\/revisions"}],"predecessor-version":[{"id":14771,"href":"https:\/\/ceca.mini.icom.museum\/es\/wp-json\/wp\/v2\/pages\/638\/revisions\/14771"}],"up":[{"embeddable":true,"href":"https:\/\/ceca.mini.icom.museum\/es\/wp-json\/wp\/v2\/pages\/137"}],"wp:attachment":[{"href":"https:\/\/ceca.mini.icom.museum\/es\/wp-json\/wp\/v2\/media?parent=638"}],"wp:term":[{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/ceca.mini.icom.museum\/es\/wp-json\/wp\/v2\/yst_prominent_words?post=638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}